{"id":8982,"date":"2023-07-29T18:21:59","date_gmt":"2023-07-29T18:21:59","guid":{"rendered":"https:\/\/www.entrerios.gov.ar\/cultura\/?p=8982"},"modified":"2023-07-29T18:22:02","modified_gmt":"2023-07-29T18:22:02","slug":"38-encuentro-entrerriano-de-teatro-visibilidad-en-roles-dentro-del-campo-teatral-para-directoras-y-dramaturgas-entrerrianas","status":"publish","type":"post","link":"https:\/\/www.entrerios.gov.ar\/cultura\/38-encuentro-entrerriano-de-teatro-visibilidad-en-roles-dentro-del-campo-teatral-para-directoras-y-dramaturgas-entrerrianas\/","title":{"rendered":"38\u00b0 Encuentro Entrerriano de Teatro:\u00a0Visibilidad en roles dentro del campo teatral para directoras y dramaturgas entrerrianas"},"content":{"rendered":"\n<p>La programaci\u00f3n de la nueva edici\u00f3n del Encuentro re\u00fane a directoras y dramaturgas de distintos puntos de la provincia. Las protagonistas repasan sus abordajes, las tramas de las historias que deciden contar -en muchos casos de manera colectiva-, y reflexionan sobre los desaf\u00edos de sus tareas art\u00edsticas en el presente. El encuentro comienza el pr\u00f3ximo jueves 3 de agosto en Concepci\u00f3n del Uruguay.&nbsp;<\/p>\n\n\n\n<p><strong>Claudia Vastos: Del trabajo colaborativo al nacimiento de un texto<\/strong><\/p>\n\n\n\n<p>\u201cEsta es mi primera experiencia, yo participo en el grupo hace muchos a\u00f1os, escribo hace mucho tiempo, pero nunca hab\u00eda tenido la oportunidad de encarar as\u00ed un trabajo. Somos un grupo que aborda con la participaci\u00f3n conjunta. A medida que fui plasmando las ideas y el camino por donde ir, fui organizando el esquema de la obra. Despu\u00e9s arrancamos con las improvisaciones y a partir de ah\u00ed fue saliendo el texto\u201d, cuenta la dramaturga Claudia Vastos haciendo referencia al Grupo Eppur Si Muove de Gualeguaych\u00fa&nbsp; que presentar\u00e1 \u201cEl agua dice\u201d.&nbsp;<\/p>\n\n\n\n<p>\u201cPor supuesto que hubo que hacer todo un trabajo de andamiaje; una vez que estaban ideadas las escenas, se propusieron palabras disparadoras de acuerdo a la escena que se iba planteando. Los actores (Joel Rocha y N\u00e9stor Gilberto) fueron armando el texto desde un trabajo cooperativo en donde est\u00e1bamos todos sumergidos en el proceso de la obra\u201d, agrega Vastos.<\/p>\n\n\n\n<p>\u201cEl agua dice\u201d plantea una escena en una playa donde un soldado de Malvinas y un obrero desaparecido, se encuentran desde un mismo tiempo y un mismo horror.<\/p>\n\n\n\n<p><strong>Patricia Velzi: M\u00e1s mujeres nos animamos a tomar la palabra escrita y la direcci\u00f3n frente a un grupo<\/strong><\/p>\n\n\n\n<p>Desde Concordia se presentar\u00e1 tambi\u00e9n la obra \u201cCuando el mundo entero dorm\u00eda\u201d (elenco concertado). Esta propuesta se centra en la historia de un personaje femenino interpretado por Rosario Correa que busca recuperar su verdadero nombre.&nbsp;<\/p>\n\n\n\n<p>\u201cLa obra que vamos a llevar al Encuentro es una dramaturgia compartida con la actriz, que a su vez es una adaptaci\u00f3n de un cuento de Edgar Allan Poe. En esta adaptaci\u00f3n lo que hicimos fue cambiarle el g\u00e9nero al protagonista y hacerlo mujer, porque nos interesaba hablar desde ese lugar. Ah\u00ed es muy claro el ejemplo de qu\u00e9 aportamos nosotras desde la direcci\u00f3n en cuanto a lo que queremos contar. Est\u00e1 la mirada de la mujer que ha sido atravesada por abusos, identidad arrebatada y cuestiones que cualquier otra mujer podr\u00eda identificarse al mirar la obra\u201d dice Patricia Velzi quien adem\u00e1s de ser co autora es la directora de la obra.<\/p>\n\n\n\n<p>Sobre la participaci\u00f3n de artistas entrerrianas en roles de direcci\u00f3n y dramaturgia la concordiense record\u00f3 y reflexion\u00f3:&nbsp; \u201cEstudi\u00e9 en la UNA (Universidad Nacional de las Artes) en Buenos Aires y toda mi formaci\u00f3n en cuanto a dramaturgos y directores fue siempre sobre varones. Mujeres, las cuento con los dedos de la mano: Patricia Zangaro, Susana Torres Molina y Griselda Gambaro. Felizmente, hace unos a\u00f1os, eso est\u00e1 cambiando. Nosotras las que podemos llevar adelante y ocupar estos lugares no tenemos que olvidar de d\u00f3nde venimos y fomentar a que eso se multiplique, no solo en m\u00e1s mujeres, sino tambi\u00e9n travestis, trans y todos quienes puedan tener un lugar importante, que su voz sea escuchada en el arte. Celebro el momento actual&nbsp; en el que estamos a nivel teatral en la provincia. Celebro mucho este Encuentro. Ojal\u00e1 se multiplique y se sostenga en el tiempo\u201d.&nbsp;<\/p>\n\n\n\n<p><strong>\u201cNostalgias\u201d desde Santa Elena, una historia vital<\/strong><\/p>\n\n\n\n<p>La obra de teatro \u201cNostalgias\u201d fue escrita para un concurso de la Biblioteca Popular Santa Elena con motivo de los 150 a\u00f1os de la ciudad, all\u00ed recibi\u00f3 un primer impulso. La puesta dram\u00e1tica narra una historia de amor en la famosa ciudad fabril entrerriana relacionada con la actividad econ\u00f3mica de la planta frigor\u00edfica que cerr\u00f3 sus puertas en 1993.<\/p>\n\n\n\n<p>\u201cSanta Elena tiene una historia del teatro de muchos a\u00f1os, no es de ahora, pero se interrumpi\u00f3 y se reinicia con esta obra\u201d cuenta la autora Marina Choternasty.<\/p>\n\n\n\n<p>\u201cLuego de recibir un est\u00edmulo en el marco del concurso me comunico con Mariela (Acosta) que ense\u00f1aba y dirig\u00eda teatro. Tomo contacto con ella y pregunto si ella se animaba a ser la directora y presentar la obra. A continuaci\u00f3n de eso comenzamos a buscar santaelenenses que quisieran participar y fue un largo camino. Recorrimos muchas instancias hasta que qued\u00f3 el elenco conformado pr\u00e1cticamente como es actualmente. A partir de ah\u00ed comienza una nueva etapa del teatro en Santa Elena\u201d.<\/p>\n\n\n\n<p>Por su parte, Mariela Acosta (directora) reflexiona: \u201cNuestro teatro es comunitario, trabajamos con personas de todas las edades. Surgi\u00f3 antes de la pandemia y nos hizo muy bien. Creo que ese es el aporte como mujeres, construir comunitariamente algo. Tenemos una impronta de la mujer que es el respeto al otro, el cari\u00f1o, la escucha. Reconstruimos nuestra propia vida a trav\u00e9s de la reconstrucci\u00f3n de la historia en el teatro. Como mujer estoy s\u00faper orgullosa de que la gente haya quedado tan sorprendida el primer d\u00eda que la presentamos, dirigida o escrita por nosotras\u201d.<\/p>\n\n\n\n<p><strong>Beatriz C\u00f3rdoba: Personajes y universos femeninos en Ar\u00edstides Vargas<\/strong><\/p>\n\n\n\n<p>\u201cSiempre admir\u00e9 la visi\u00f3n que tiene Ar\u00edstides Vargas de la mujer, que no es la mirada cl\u00e1sica del hombre. Tiene un conocimiento de la psiquis y del alma de la mujer muy interesante y obviamente, la combino con mi interpretaci\u00f3n y con c\u00f3mo yo lo veo\u201d subraya Beatriz C\u00f3rdoba, co autora, directora y actriz de \u201cLas Mujeres de Ar\u00edstides\u201d del Grupo Teatro El Eclipse (Col\u00f3n). C\u00f3rdoba hizo, dirigi\u00f3 y ense\u00f1\u00f3 teatro en Nueva York por mucho tiempo. Hace siete a\u00f1os volvi\u00f3 a la Argentina y se radic\u00f3 en Col\u00f3n donde &#8211; un a\u00f1o m\u00e1s tarde &#8211; inici\u00f3 su compa\u00f1\u00eda El Eclipse de teatro independiente.<\/p>\n\n\n\n<p>\u201cAl dirigir veo que la gente me respeta mucho, pero hay una cierta preferencia al director hombre. Eso est\u00e1 cambiando con mi gente porque saben que mi visi\u00f3n de las cosas es m\u00eda, independiente del sexo. Pero s\u00ed creo que hay una manera de abordar la tem\u00e1tica, los personajes y el material a trav\u00e9s de una visi\u00f3n puramente de la mujer. Eso es indudable\u201d.&nbsp;<\/p>\n\n\n\n<p>\u201cMe di cuenta que en todas las obras que dirig\u00ed en Nueva York y las que dirijo ac\u00e1, casi siempre son de autoras o el personaje principal es una mujer. Dirig\u00ed El Disparo de la autora uruguaya Estela Golovchenko, y el personaje principal es una mujer. Tambi\u00e9n trabaj\u00e9 con Mano a Mano de la escritora ecuatoriana Viviana Cordero, en donde tambi\u00e9n las dos protagonistas son mujeres. Me doy cuenta que es importante representar a la mujer porque veo que no est\u00e1 suficientemente en el escenario, y si lo est\u00e1, est\u00e1 representada a trav\u00e9s de una visi\u00f3n masculina y a lo mejor machista\u201d, reflexion\u00f3.<\/p>\n\n\n\n<p>Para despedirse dijo: \u201cEstoy muy contenta y emocionada de ser parte del Encuentro Entrerriano de Teatro, es muy importante para mi participar\u201d.&nbsp;<\/p>\n\n\n\n<p>En el unipersonal los diez personajes muestran la visi\u00f3n \u00fanica que Ar\u00edstides Vargas tiene sobre la identidad femenina. En las escenas se podr\u00e1n ver a mujeres compartiendo sus sue\u00f1os, recuerdos, frustraciones, humor, rabia, poes\u00eda, soledad y locura.<\/p>\n\n\n\n<p><strong>Daniela Osella: Dispositivos de poder, y tensiones en la creaci\u00f3n art\u00edstica y construcci\u00f3n de nuevas relaciones grupales<\/strong><\/p>\n\n\n\n<p>\u201cLos roles que ejercemos las teatristas entrerrianas hace a\u00f1os, no es algo nuevo, sino que ahora se nos da otra visibilidad y eso tambi\u00e9n nos permite reconocernos como hacedoras de esas pr\u00e1cticas. El marco sociocultural, de transformaciones sociales, est\u00e1 relacionado con esa visibilizaci\u00f3n de las pr\u00e1cticas desarrolladas por mujeres. Nos permite a nosotras posicionarnos en ese lugar, asumirnos en ese lugar\u201d dice Daniela Osella, co directora junto a Victoria Rold\u00e1n de la obra \u201cManada\u201d (Paran\u00e1).<\/p>\n\n\n\n<p>\u201cSoy bastante esc\u00e9ptica de pensar que hay solo una cuesti\u00f3n de g\u00e9nero atravesando las operaciones que manejan los dispositivos de poder y c\u00f3mo se opera sobre las tensiones que implica una creaci\u00f3n art\u00edstica, y las relaciones hacia adentro de los equipos. Creo que el hecho de que haya una mujer no garantiza nada, sino lo que realmente importa es c\u00f3mo nos relacionamos en el interior de los equipos de trabajo, qu\u00e9 lugares y qu\u00e9 maneras construimos all\u00ed. Creo que tiene que ver m\u00e1s con eso que con nuestro g\u00e9nero. Desde mi perspectiva, lo entiendo desde una manera colectiva, m\u00e1s all\u00e1 de que haya roles con funciones que se van acordando hacia el centro de cada grupalidad\u201d.&nbsp;<\/p>\n\n\n\n<p>\u201cManada\u201d es una creaci\u00f3n colectiva de la que son parte \u00c1ngela Mart\u00ednez, Sabina Piccini, Juan Cruz Rivasseau, Pablo Vallejo y Carla Sof\u00eda Bernhardt, adem\u00e1s de las directoras.<\/p>\n\n\n\n<p><strong>Relacionadas para agendar<\/strong><\/p>\n\n\n\n<p>En el marco del Encuentro -que comienza este jueves 3 y que se extender\u00e1 hasta el domingo 6 impulsado por la Secretar\u00eda de Cultura de la Provincia y el Municipio de Concepci\u00f3n del Uruguay- tambi\u00e9n se desarrollar\u00e1 una charla&nbsp;\u201cPerspectiva de g\u00e9nero en el trabajo esc\u00e9nico\u201d&nbsp; Mesa de di\u00e1logo entre la comunidad teatral entrerriana e integrantes y participantes de \u201cUna escena propia\u201d (Mery Palacios y Gabriela Trevisani). Ser\u00e1 en Las&nbsp;Yotivenco Espacio Teatral el viernes 4 de agosto a las 14 hs.<\/p>\n\n\n\n<p>Todas las actividades del Encuentro se desarrollar\u00e1n con entrada libre y gratuita.<\/p>\n\n\n\n<p><strong>PROGRAMACI\u00d3N del Encuentro Entrerriano de teatro disponible\u00a0<a href=\"https:\/\/drive.google.com\/file\/d\/15wlpNYWQ5ZA4lqrgqR83zbkFMV79ChVc\/view\">AQU\u00cd<\/a><\/strong><\/p>\n\n\n\n<p><em>Foto: Archivo SCER_Encuentro Entrerriano de Teatro 2022<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La programaci\u00f3n de la nueva edici\u00f3n del Encuentro re\u00fane a directoras y dramaturgas de distintos puntos de la provincia. Las protagonistas repasan sus abordajes, las tramas de las historias que deciden contar -en muchos casos de manera colectiva-, y reflexionan sobre los desaf\u00edos de sus tareas art\u00edsticas en el presente. El encuentro comienza el pr\u00f3ximo [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":8983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,28],"tags":[],"class_list":["post-8982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/posts\/8982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/comments?post=8982"}],"version-history":[{"count":1,"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/posts\/8982\/revisions"}],"predecessor-version":[{"id":8984,"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/posts\/8982\/revisions\/8984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/media\/8983"}],"wp:attachment":[{"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/media?parent=8982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/categories?post=8982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entrerios.gov.ar\/cultura\/wp-json\/wp\/v2\/tags?post=8982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}